{"id":728,"date":"2024-03-28T10:37:00","date_gmt":"2024-03-28T13:37:00","guid":{"rendered":"https:\/\/demo.athemes.com\/sydney-main\/?p=728"},"modified":"2024-09-07T00:14:17","modified_gmt":"2024-09-07T03:14:17","slug":"excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro","status":"publish","type":"post","link":"https:\/\/excelft.com\/blog\/excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro\/","title":{"rendered":"EXCELbr anuncia a distribui\u00e7\u00e3o da empresa Franklin Fueling para todo o mercado brasileiro"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>Parceria mostra for\u00e7a da EXCELbr no mercado ao prover solu\u00e7\u00f5es para toda cadeia de distribui\u00e7\u00e3o e venda de combust\u00edvel no Brasil<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A EXCELbr, um dos l\u00edderes globais em solu\u00e7\u00f5es para gest\u00e3o do abastecimento de combust\u00edveis e calibradores de pneus, fecha a distribui\u00e7\u00e3o para todo o mercado brasileiro da empresa Franklin Fueling.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Franklin Fueling \u00e9 uma empresa l\u00edder global na produ\u00e7\u00e3o e comercializa\u00e7\u00e3o de sistemas e componentes para movimenta\u00e7\u00e3o de \u00e1gua e combust\u00edveis automotivos. Oferecem uma linha completa de equipamentos petrol\u00edferos do mundo, incluindo sistemas de bombeamento submers\u00edveis, sistemas de tubula\u00e7\u00e3o e conten\u00e7\u00e3o,&nbsp;<em>hardware<\/em>&nbsp;para esta\u00e7\u00f5es de servi\u00e7o, sistemas de distribui\u00e7\u00e3o, sistemas supressores de vapor e sistemas de transporte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEste movimento com a Franklin Fueling somados com a compra da xptec e a parceria com a LEPAM Equipamentos direciona a EXCELbr rumo a uma empresa&nbsp;<em>One Stop Shop<\/em>&nbsp;no mercado de combust\u00edvel no Brasil, ou seja, passaremos a oferecer toda solu\u00e7\u00e3o e controle de abastecimento para o mercado de Postos de Combust\u00edvel Interno e Externo. Isso ir\u00e1 possibilitar in\u00fameras oportunidades de neg\u00f3cio e fortalecimento da marca\u201d, explica Cristian Bazaga, CEO da EXCELbr.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uma das especialidades da Franklin Fueling \u00e9 a fabrica\u00e7\u00e3o de bombas submers\u00edveis e este tipo de bomba \u00e9 capaz de manusear diversos materiais como \u00e1guas residuais, areia, lama, chorume, entre outros. As bombas submers\u00edveis s\u00e3o, geralmente, confi\u00e1veis e capazes de operar bem em condi\u00e7\u00f5es adversas. Algumas das suas principais aplica\u00e7\u00f5es s\u00e3o tratamento de esgoto, dragagem e minera\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com a solu\u00e7\u00e3o de Bomba Submersa da Franklin, al\u00e9m das Sondas de Medi\u00e7\u00e3o de Combust\u00edvel Flex\u00edvel (para tanques at\u00e9 20 metros de altura) presente no portf\u00f3lio da xptec, o mercado de Bases de Distribui\u00e7\u00e3o de Combust\u00edveis e de TRR&#8217;s (Transportador Retalhista de Combust\u00edvel) se abrem, possibilitando o forte posicionamento da EXCELbr ao prover solu\u00e7\u00e3o para toda cadeia de distribui\u00e7\u00e3o e venda de combust\u00edvel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sobre EXCELbr<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A EXCELbr \u00e9 uma empresa brasileira reconhecida por suas solu\u00e7\u00f5es inovadoras e qualidade avan\u00e7ada desde 1990. Pioneira no desenvolvimento do primeiro calibrador digital de pneus, tornou-se uma das l\u00edderes em controle de abastecimento de combust\u00edvel, gest\u00e3o de frotas, medi\u00e7\u00e3o de tanques de combust\u00edveis e monitoramento ambiental. Com mais de 120 colaboradores diretos, a EXCELbr promove a diversidade e inclus\u00e3o, buscando inspirar e desenvolver talentos em um ambiente de trabalho respeitoso e alegre.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sobre a Franklin Fueling<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Franklin Fueling foi fundada em 1944 e o&nbsp;primeiro produto da empresa foi um gerador de mochila para alimentar os equipamentos de r\u00e1dio dos paraquedistas usados \u200b\u200b\u200b\u200bdurante a Segunda Guerra Mundial. Desenvolvida no final da d\u00e9cada de 1960, a bomba submers\u00edvel de transfer\u00eancia de combust\u00edvel da empresa foi a primeira bomba submers\u00edvel deste tipo e desempenhou um papel de lideran\u00e7a na tend\u00eancia para o armazenamento subterr\u00e2neo de produtos petrol\u00edferos. Atualmente, fornecem aos comerciantes de petr\u00f3leo, distribuidores, instaladores e manuten\u00e7\u00e3o o Total System Solution\u2122.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Parceria mostra for\u00e7a da EXCELbr no mercado ao prover solu\u00e7\u00f5es para toda cadeia de distribui\u00e7\u00e3o e venda de combust\u00edvel no [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":771,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EXCELbr anuncia a distribui\u00e7\u00e3o da empresa Franklin Fueling para todo o mercado brasileiro - EXCEL - blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/excelft.com\/blog\/excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EXCELbr anuncia a distribui\u00e7\u00e3o da empresa Franklin Fueling para todo o mercado brasileiro - EXCEL - blog\" \/>\n<meta property=\"og:description\" content=\"Parceria mostra for\u00e7a da EXCELbr no mercado ao prover solu\u00e7\u00f5es para toda cadeia de distribui\u00e7\u00e3o e venda de combust\u00edvel no [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/excelft.com\/blog\/excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro\/\" \/>\n<meta property=\"og:site_name\" content=\"EXCEL - blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/excelfueling\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-28T13:37:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-07T03:14:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/excelft.com\/blog\/wp-content\/uploads\/2021\/11\/blog-excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro-907d0d8134.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Excelbr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Excelbr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro\\\/\"},\"author\":{\"name\":\"Excelbr\",\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/#\\\/schema\\\/person\\\/c16241bead34264d4bed13f3d08e43d4\"},\"headline\":\"EXCELbr anuncia a distribui\u00e7\u00e3o da empresa Franklin Fueling para todo o mercado brasileiro\",\"datePublished\":\"2024-03-28T13:37:00+00:00\",\"dateModified\":\"2024-09-07T03:14:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro\\\/\"},\"wordCount\":544,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/excelft.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/blog-excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro-907d0d8134.jpg\",\"articleSection\":[\"Geral\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/excelft.com\\\/blog\\\/excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro\\\/\",\"url\":\"https:\\\/\\\/excelft.com\\\/blog\\\/excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro\\\/\",\"name\":\"EXCELbr anuncia a distribui\u00e7\u00e3o da empresa Franklin Fueling para todo o mercado brasileiro - EXCEL - blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/excelft.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/blog-excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro-907d0d8134.jpg\",\"datePublished\":\"2024-03-28T13:37:00+00:00\",\"dateModified\":\"2024-09-07T03:14:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/excelft.com\\\/blog\\\/excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/excelft.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/blog-excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro-907d0d8134.jpg\",\"contentUrl\":\"https:\\\/\\\/excelft.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/blog-excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro-907d0d8134.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/excelft.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EXCELbr anuncia a distribui\u00e7\u00e3o da empresa Franklin Fueling para todo o mercado brasileiro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/excelft.com\\\/blog\\\/\",\"name\":\"EXCEL - blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/excelft.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/#organization\",\"name\":\"EXCEL - blog\",\"url\":\"https:\\\/\\\/excelft.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/excelft.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/logo-excel.svg\",\"contentUrl\":\"https:\\\/\\\/excelft.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/logo-excel.svg\",\"width\":307,\"height\":69,\"caption\":\"EXCEL - blog\"},\"image\":{\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/excelfueling\",\"https:\\\/\\\/www.instagram.com\\\/excelfueling\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/excelfueling\\\/?originalSubdomain=br\",\"https:\\\/\\\/www.youtube.com\\\/excelfueling\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/#\\\/schema\\\/person\\\/c16241bead34264d4bed13f3d08e43d4\",\"name\":\"Excelbr\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe7094acce8e1b37ade139ea296076c201aa729da7efc22f68286dfdede38d99?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe7094acce8e1b37ade139ea296076c201aa729da7efc22f68286dfdede38d99?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe7094acce8e1b37ade139ea296076c201aa729da7efc22f68286dfdede38d99?s=96&d=mm&r=g\",\"caption\":\"Excelbr\"},\"sameAs\":[\"https:\\\/\\\/excelft.com\\\/blog\"],\"url\":\"https:\\\/\\\/excelft.com\\\/blog\\\/author\\\/excelf64_blog\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EXCELbr anuncia a distribui\u00e7\u00e3o da empresa Franklin Fueling para todo o mercado brasileiro - EXCEL - blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/excelft.com\/blog\/excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro\/","og_locale":"pt_BR","og_type":"article","og_title":"EXCELbr anuncia a distribui\u00e7\u00e3o da empresa Franklin Fueling para todo o mercado brasileiro - EXCEL - blog","og_description":"Parceria mostra for\u00e7a da EXCELbr no mercado ao prover solu\u00e7\u00f5es para toda cadeia de distribui\u00e7\u00e3o e venda de combust\u00edvel no [&hellip;]","og_url":"https:\/\/excelft.com\/blog\/excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro\/","og_site_name":"EXCEL - blog","article_publisher":"https:\/\/www.facebook.com\/excelfueling","article_published_time":"2024-03-28T13:37:00+00:00","article_modified_time":"2024-09-07T03:14:17+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/excelft.com\/blog\/wp-content\/uploads\/2021\/11\/blog-excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro-907d0d8134.jpg","type":"image\/jpeg"}],"author":"Excelbr","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Excelbr","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/excelft.com\/blog\/excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro\/#article","isPartOf":{"@id":"https:\/\/excelft.com\/blog\/excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro\/"},"author":{"name":"Excelbr","@id":"https:\/\/excelft.com\/blog\/#\/schema\/person\/c16241bead34264d4bed13f3d08e43d4"},"headline":"EXCELbr anuncia a distribui\u00e7\u00e3o da empresa Franklin Fueling para todo o mercado brasileiro","datePublished":"2024-03-28T13:37:00+00:00","dateModified":"2024-09-07T03:14:17+00:00","mainEntityOfPage":{"@id":"https:\/\/excelft.com\/blog\/excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro\/"},"wordCount":544,"commentCount":0,"publisher":{"@id":"https:\/\/excelft.com\/blog\/#organization"},"image":{"@id":"https:\/\/excelft.com\/blog\/excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro\/#primaryimage"},"thumbnailUrl":"https:\/\/excelft.com\/blog\/wp-content\/uploads\/2021\/11\/blog-excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro-907d0d8134.jpg","articleSection":["Geral"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/excelft.com\/blog\/excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/excelft.com\/blog\/excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro\/","url":"https:\/\/excelft.com\/blog\/excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro\/","name":"EXCELbr anuncia a distribui\u00e7\u00e3o da empresa Franklin Fueling para todo o mercado brasileiro - EXCEL - blog","isPartOf":{"@id":"https:\/\/excelft.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/excelft.com\/blog\/excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro\/#primaryimage"},"image":{"@id":"https:\/\/excelft.com\/blog\/excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro\/#primaryimage"},"thumbnailUrl":"https:\/\/excelft.com\/blog\/wp-content\/uploads\/2021\/11\/blog-excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro-907d0d8134.jpg","datePublished":"2024-03-28T13:37:00+00:00","dateModified":"2024-09-07T03:14:17+00:00","breadcrumb":{"@id":"https:\/\/excelft.com\/blog\/excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/excelft.com\/blog\/excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/excelft.com\/blog\/excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro\/#primaryimage","url":"https:\/\/excelft.com\/blog\/wp-content\/uploads\/2021\/11\/blog-excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro-907d0d8134.jpg","contentUrl":"https:\/\/excelft.com\/blog\/wp-content\/uploads\/2021\/11\/blog-excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro-907d0d8134.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/excelft.com\/blog\/excelbr-anuncia-a-distribuicao-da-empresa-franklin-fueling-para-todo-o-mercado-brasileiro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/excelft.com\/blog\/"},{"@type":"ListItem","position":2,"name":"EXCELbr anuncia a distribui\u00e7\u00e3o da empresa Franklin Fueling para todo o mercado brasileiro"}]},{"@type":"WebSite","@id":"https:\/\/excelft.com\/blog\/#website","url":"https:\/\/excelft.com\/blog\/","name":"EXCEL - blog","description":"","publisher":{"@id":"https:\/\/excelft.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/excelft.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/excelft.com\/blog\/#organization","name":"EXCEL - blog","url":"https:\/\/excelft.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/excelft.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/logo-excel.svg","contentUrl":"https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/logo-excel.svg","width":307,"height":69,"caption":"EXCEL - blog"},"image":{"@id":"https:\/\/excelft.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/excelfueling","https:\/\/www.instagram.com\/excelfueling","https:\/\/www.linkedin.com\/company\/excelfueling\/?originalSubdomain=br","https:\/\/www.youtube.com\/excelfueling"]},{"@type":"Person","@id":"https:\/\/excelft.com\/blog\/#\/schema\/person\/c16241bead34264d4bed13f3d08e43d4","name":"Excelbr","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/fe7094acce8e1b37ade139ea296076c201aa729da7efc22f68286dfdede38d99?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fe7094acce8e1b37ade139ea296076c201aa729da7efc22f68286dfdede38d99?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe7094acce8e1b37ade139ea296076c201aa729da7efc22f68286dfdede38d99?s=96&d=mm&r=g","caption":"Excelbr"},"sameAs":["https:\/\/excelft.com\/blog"],"url":"https:\/\/excelft.com\/blog\/author\/excelf64_blog\/"}]}},"_links":{"self":[{"href":"https:\/\/excelft.com\/blog\/wp-json\/wp\/v2\/posts\/728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/excelft.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/excelft.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/excelft.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/excelft.com\/blog\/wp-json\/wp\/v2\/comments?post=728"}],"version-history":[{"count":2,"href":"https:\/\/excelft.com\/blog\/wp-json\/wp\/v2\/posts\/728\/revisions"}],"predecessor-version":[{"id":773,"href":"https:\/\/excelft.com\/blog\/wp-json\/wp\/v2\/posts\/728\/revisions\/773"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/excelft.com\/blog\/wp-json\/wp\/v2\/media\/771"}],"wp:attachment":[{"href":"https:\/\/excelft.com\/blog\/wp-json\/wp\/v2\/media?parent=728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/excelft.com\/blog\/wp-json\/wp\/v2\/categories?post=728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/excelft.com\/blog\/wp-json\/wp\/v2\/tags?post=728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}