{"id":1036,"date":"2022-10-01T16:57:00","date_gmt":"2022-10-01T19:57:00","guid":{"rendered":"https:\/\/excelft.com\/blog\/?p=1036"},"modified":"2024-09-08T16:59:44","modified_gmt":"2024-09-08T19:59:44","slug":"excelbr-na-expopostos-2022","status":"publish","type":"post","link":"https:\/\/excelft.com\/blog\/excelbr-na-expopostos-2022\/","title":{"rendered":"EXCELbr na Expopostos 2022"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>A EXCELbr trouxe para a maior feira do setor suas solu\u00e7\u00f5es e novidades para o p\u00fablico<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s tr\u00eas anos de pausa por conta da pandemia, a&nbsp;<a href=\"https:\/\/expopostos.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">Expopostos<\/a>&nbsp;retornou quebrando todos os recordes das edi\u00e7\u00f5es anteriores. A 15\u00aa Feira e F\u00f3rum Internacional ExpoPostos &amp; Conveni\u00eancia, no final de julho, refletiu o momento otimista que vive o varejo de combust\u00edveis e conveni\u00eancia. E claro, n\u00f3s estivemos presentes na maior feira do setor. Confira na mat\u00e9ria como foi a EXCELbr na Expopostos 2022!<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"799\" height=\"534\" src=\"https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/post-excelbr-expopostos-2022-169652954026.jpg\" alt=\"\" class=\"wp-image-1037\" srcset=\"https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/post-excelbr-expopostos-2022-169652954026.jpg 799w, https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/post-excelbr-expopostos-2022-169652954026-300x201.jpg 300w, https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/post-excelbr-expopostos-2022-169652954026-768x513.jpg 768w, https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/post-excelbr-expopostos-2022-169652954026-230x154.jpg 230w, https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/post-excelbr-expopostos-2022-169652954026-350x234.jpg 350w, https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/post-excelbr-expopostos-2022-169652954026-480x321.jpg 480w\" sizes=\"(max-width: 799px) 100vw, 799px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Cr\u00e9ditos: Site Expopostos<\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">A edi\u00e7\u00e3o dos recordes<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O p\u00fablico presente na 15\u00aa Expopostos teve a oportunidade de conhecer as mais recentes solu\u00e7\u00f5es de mais de 200 marcas (n\u00famero de ades\u00e3o 35% maior do que a \u00faltima edi\u00e7\u00e3o). Al\u00e9m disso, foram mais de 45 horas de conte\u00fado qualificado espalhados nos 25 mil m\u00b2 de exposi\u00e7\u00e3o (crescimento de 15% ante 2019), no pavilh\u00e3o da S\u00e3o Paulo Expo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m da feira com in\u00fameros estandes, tivemos palestras e debates no F\u00f3rum Internacional e na Arena do conhecimento. Isso tudo acontecendo paralelamente a feira. Os temas debatidos foram:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>A evolu\u00e7\u00e3o do varejo de conveni\u00eancia;<\/li>\n\n\n\n<li>A matriz energ\u00e9tica brasileira e ve\u00edculos el\u00e9tricos;<\/li>\n\n\n\n<li>O comportamento do consumidor;<\/li>\n\n\n\n<li>Gest\u00e3o de neg\u00f3cios com foco em resultados;<\/li>\n\n\n\n<li>ESG (governan\u00e7a ambiental, social e corporativa);<\/li>\n\n\n\n<li>As opera\u00e7\u00f5es nas revendas na Am\u00e9rica Latina e as tend\u00eancias tecnol\u00f3gicas do setor.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo os organizadores da feira, 95% dos expositores afirmam que o evento correspondeu ou superou as suas expectativas e 93% das marcas expositoras classificam a qualidade dos visitantes do evento como acima das expectativas. Em outras palavras, a feira foi um completo sucesso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>EXCELbr na Expopostos 2022<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/post-excelbr-expopostos-2022-1696529541838.jpg\" alt=\"\" class=\"wp-image-1038\" srcset=\"https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/post-excelbr-expopostos-2022-1696529541838.jpg 800w, https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/post-excelbr-expopostos-2022-1696529541838-300x200.jpg 300w, https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/post-excelbr-expopostos-2022-1696529541838-768x512.jpg 768w, https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/post-excelbr-expopostos-2022-1696529541838-230x153.jpg 230w, https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/post-excelbr-expopostos-2022-1696529541838-350x233.jpg 350w, https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/post-excelbr-expopostos-2022-1696529541838-480x320.jpg 480w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Equipe na Expopostos 2022<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Primeiramente, presente nos principais eventos do setor, a EXCELbr fez uma grande participa\u00e7\u00e3o na Expopostos. Em suma, contamos com um bel\u00edssimo estande personalizado com as nossas cores, produtos e um grande lan\u00e7amento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Levamos ao p\u00fablico nossas solu\u00e7\u00f5es como: ELS, o sistema de monitoramento ambiental, os calibradores digitais de pneus PNT, o Monitor de Vazamento (MV), Medidor de Tanque \u00danico (MTU), o IMT e por \u00faltimo e n\u00e3o menos importante, o nosso lan\u00e7amento CEV Light.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/post-excelbr-expopostos-2022-1696529542372.jpg\" alt=\"\" class=\"wp-image-1039\" srcset=\"https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/post-excelbr-expopostos-2022-1696529542372.jpg 800w, https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/post-excelbr-expopostos-2022-1696529542372-300x200.jpg 300w, https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/post-excelbr-expopostos-2022-1696529542372-768x512.jpg 768w, https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/post-excelbr-expopostos-2022-1696529542372-230x153.jpg 230w, https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/post-excelbr-expopostos-2022-1696529542372-350x233.jpg 350w, https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/post-excelbr-expopostos-2022-1696529542372-480x320.jpg 480w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Trouxemos v\u00e1rias solu\u00e7\u00f5es para a feira<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s uma longa espera de 3 anos, participamos da 15\u00aa edi\u00e7\u00e3o da maior feira do setor. Foram 3 dias de feira bem intensos e de muito trabalho. Tivemos visitas, reencontros, networking e principalmente acelera\u00e7\u00e3o dos neg\u00f3cios com os nossos clientes. A Expopostos j\u00e1 \u00e9 uma tradi\u00e7\u00e3o EXCELbr e sentimos orgulhosos que obtivemos \u00f3timos resultados com a feira.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/post-excelbr-expopostos-2022-1696529543585.jpg\" alt=\"\" class=\"wp-image-1040\" srcset=\"https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/post-excelbr-expopostos-2022-1696529543585.jpg 800w, https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/post-excelbr-expopostos-2022-1696529543585-300x200.jpg 300w, https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/post-excelbr-expopostos-2022-1696529543585-768x512.jpg 768w, https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/post-excelbr-expopostos-2022-1696529543585-230x153.jpg 230w, https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/post-excelbr-expopostos-2022-1696529543585-350x233.jpg 350w, https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/post-excelbr-expopostos-2022-1696529543585-480x320.jpg 480w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Sistema ELS<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mas o trabalho come\u00e7ou muito antes disso! Por fim, foram meses de planejamento, reuni\u00f5es e um \u00f3timo trabalho em equipe de todos os setores, desde a produ\u00e7\u00e3o dos equipamentos at\u00e9 a instala\u00e7\u00e3o. Acima de tudo, agradecemos a todos voc\u00eas pela dedica\u00e7\u00e3o, carinho e cuidado em fazer essa feira acontecer. Muito obrigado aos nossos clientes e parceiros pela presen\u00e7a e j\u00e1 estamos nos preparando para a pr\u00f3xima edi\u00e7\u00e3o.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/post-excelbr-expopostos-2022-1696529544878.jpg\" alt=\"\" class=\"wp-image-1041\" srcset=\"https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/post-excelbr-expopostos-2022-1696529544878.jpg 800w, https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/post-excelbr-expopostos-2022-1696529544878-300x200.jpg 300w, https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/post-excelbr-expopostos-2022-1696529544878-768x512.jpg 768w, https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/post-excelbr-expopostos-2022-1696529544878-230x153.jpg 230w, https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/post-excelbr-expopostos-2022-1696529544878-350x233.jpg 350w, https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/post-excelbr-expopostos-2022-1696529544878-480x320.jpg 480w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Cristian Bazaga, CEO da EXCELbr junto da nossa equipe<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A EXCELbr trouxe para a maior feira do setor suas solu\u00e7\u00f5es e novidades para o p\u00fablico. Ap\u00f3s tr\u00eas anos de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1043,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1036","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EXCELbr na Expopostos 2022 - EXCEL - blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/excelft.com\/blog\/excelbr-na-expopostos-2022\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EXCELbr na Expopostos 2022 - EXCEL - blog\" \/>\n<meta property=\"og:description\" content=\"A EXCELbr trouxe para a maior feira do setor suas solu\u00e7\u00f5es e novidades para o p\u00fablico. Ap\u00f3s tr\u00eas anos de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/excelft.com\/blog\/excelbr-na-expopostos-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"EXCEL - blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/excelfueling\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-01T19:57:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-08T19:59:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/excelft.com\/blog\/wp-content\/uploads\/2022\/10\/cover-excelbr-expopostos-2022-169652954680.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Excelbr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Excelbr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/excelbr-na-expopostos-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/excelbr-na-expopostos-2022\\\/\"},\"author\":{\"name\":\"Excelbr\",\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/#\\\/schema\\\/person\\\/c16241bead34264d4bed13f3d08e43d4\"},\"headline\":\"EXCELbr na Expopostos 2022\",\"datePublished\":\"2022-10-01T19:57:00+00:00\",\"dateModified\":\"2024-09-08T19:59:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/excelbr-na-expopostos-2022\\\/\"},\"wordCount\":531,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/excelbr-na-expopostos-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/excelft.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/cover-excelbr-expopostos-2022-169652954680.jpg\",\"articleSection\":[\"Geral\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/excelft.com\\\/blog\\\/excelbr-na-expopostos-2022\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/excelbr-na-expopostos-2022\\\/\",\"url\":\"https:\\\/\\\/excelft.com\\\/blog\\\/excelbr-na-expopostos-2022\\\/\",\"name\":\"EXCELbr na Expopostos 2022 - EXCEL - blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/excelbr-na-expopostos-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/excelbr-na-expopostos-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/excelft.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/cover-excelbr-expopostos-2022-169652954680.jpg\",\"datePublished\":\"2022-10-01T19:57:00+00:00\",\"dateModified\":\"2024-09-08T19:59:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/excelbr-na-expopostos-2022\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/excelft.com\\\/blog\\\/excelbr-na-expopostos-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/excelbr-na-expopostos-2022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/excelft.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/cover-excelbr-expopostos-2022-169652954680.jpg\",\"contentUrl\":\"https:\\\/\\\/excelft.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/cover-excelbr-expopostos-2022-169652954680.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/excelbr-na-expopostos-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/excelft.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EXCELbr na Expopostos 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/excelft.com\\\/blog\\\/\",\"name\":\"EXCEL - blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/excelft.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/#organization\",\"name\":\"EXCEL - blog\",\"url\":\"https:\\\/\\\/excelft.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/excelft.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/logo-excel.svg\",\"contentUrl\":\"https:\\\/\\\/excelft.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/logo-excel.svg\",\"width\":307,\"height\":69,\"caption\":\"EXCEL - blog\"},\"image\":{\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/excelfueling\",\"https:\\\/\\\/www.instagram.com\\\/excelfueling\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/excelfueling\\\/?originalSubdomain=br\",\"https:\\\/\\\/www.youtube.com\\\/excelfueling\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/#\\\/schema\\\/person\\\/c16241bead34264d4bed13f3d08e43d4\",\"name\":\"Excelbr\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe7094acce8e1b37ade139ea296076c201aa729da7efc22f68286dfdede38d99?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe7094acce8e1b37ade139ea296076c201aa729da7efc22f68286dfdede38d99?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe7094acce8e1b37ade139ea296076c201aa729da7efc22f68286dfdede38d99?s=96&d=mm&r=g\",\"caption\":\"Excelbr\"},\"sameAs\":[\"https:\\\/\\\/excelft.com\\\/blog\"],\"url\":\"https:\\\/\\\/excelft.com\\\/blog\\\/author\\\/excelf64_blog\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EXCELbr na Expopostos 2022 - EXCEL - blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/excelft.com\/blog\/excelbr-na-expopostos-2022\/","og_locale":"pt_BR","og_type":"article","og_title":"EXCELbr na Expopostos 2022 - EXCEL - blog","og_description":"A EXCELbr trouxe para a maior feira do setor suas solu\u00e7\u00f5es e novidades para o p\u00fablico. Ap\u00f3s tr\u00eas anos de [&hellip;]","og_url":"https:\/\/excelft.com\/blog\/excelbr-na-expopostos-2022\/","og_site_name":"EXCEL - blog","article_publisher":"https:\/\/www.facebook.com\/excelfueling","article_published_time":"2022-10-01T19:57:00+00:00","article_modified_time":"2024-09-08T19:59:44+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/excelft.com\/blog\/wp-content\/uploads\/2022\/10\/cover-excelbr-expopostos-2022-169652954680.jpg","type":"image\/jpeg"}],"author":"Excelbr","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Excelbr","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/excelft.com\/blog\/excelbr-na-expopostos-2022\/#article","isPartOf":{"@id":"https:\/\/excelft.com\/blog\/excelbr-na-expopostos-2022\/"},"author":{"name":"Excelbr","@id":"https:\/\/excelft.com\/blog\/#\/schema\/person\/c16241bead34264d4bed13f3d08e43d4"},"headline":"EXCELbr na Expopostos 2022","datePublished":"2022-10-01T19:57:00+00:00","dateModified":"2024-09-08T19:59:44+00:00","mainEntityOfPage":{"@id":"https:\/\/excelft.com\/blog\/excelbr-na-expopostos-2022\/"},"wordCount":531,"commentCount":0,"publisher":{"@id":"https:\/\/excelft.com\/blog\/#organization"},"image":{"@id":"https:\/\/excelft.com\/blog\/excelbr-na-expopostos-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/excelft.com\/blog\/wp-content\/uploads\/2022\/10\/cover-excelbr-expopostos-2022-169652954680.jpg","articleSection":["Geral"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/excelft.com\/blog\/excelbr-na-expopostos-2022\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/excelft.com\/blog\/excelbr-na-expopostos-2022\/","url":"https:\/\/excelft.com\/blog\/excelbr-na-expopostos-2022\/","name":"EXCELbr na Expopostos 2022 - EXCEL - blog","isPartOf":{"@id":"https:\/\/excelft.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/excelft.com\/blog\/excelbr-na-expopostos-2022\/#primaryimage"},"image":{"@id":"https:\/\/excelft.com\/blog\/excelbr-na-expopostos-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/excelft.com\/blog\/wp-content\/uploads\/2022\/10\/cover-excelbr-expopostos-2022-169652954680.jpg","datePublished":"2022-10-01T19:57:00+00:00","dateModified":"2024-09-08T19:59:44+00:00","breadcrumb":{"@id":"https:\/\/excelft.com\/blog\/excelbr-na-expopostos-2022\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/excelft.com\/blog\/excelbr-na-expopostos-2022\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/excelft.com\/blog\/excelbr-na-expopostos-2022\/#primaryimage","url":"https:\/\/excelft.com\/blog\/wp-content\/uploads\/2022\/10\/cover-excelbr-expopostos-2022-169652954680.jpg","contentUrl":"https:\/\/excelft.com\/blog\/wp-content\/uploads\/2022\/10\/cover-excelbr-expopostos-2022-169652954680.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/excelft.com\/blog\/excelbr-na-expopostos-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/excelft.com\/blog\/"},{"@type":"ListItem","position":2,"name":"EXCELbr na Expopostos 2022"}]},{"@type":"WebSite","@id":"https:\/\/excelft.com\/blog\/#website","url":"https:\/\/excelft.com\/blog\/","name":"EXCEL - blog","description":"","publisher":{"@id":"https:\/\/excelft.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/excelft.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/excelft.com\/blog\/#organization","name":"EXCEL - blog","url":"https:\/\/excelft.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/excelft.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/logo-excel.svg","contentUrl":"https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/logo-excel.svg","width":307,"height":69,"caption":"EXCEL - blog"},"image":{"@id":"https:\/\/excelft.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/excelfueling","https:\/\/www.instagram.com\/excelfueling","https:\/\/www.linkedin.com\/company\/excelfueling\/?originalSubdomain=br","https:\/\/www.youtube.com\/excelfueling"]},{"@type":"Person","@id":"https:\/\/excelft.com\/blog\/#\/schema\/person\/c16241bead34264d4bed13f3d08e43d4","name":"Excelbr","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/fe7094acce8e1b37ade139ea296076c201aa729da7efc22f68286dfdede38d99?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fe7094acce8e1b37ade139ea296076c201aa729da7efc22f68286dfdede38d99?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe7094acce8e1b37ade139ea296076c201aa729da7efc22f68286dfdede38d99?s=96&d=mm&r=g","caption":"Excelbr"},"sameAs":["https:\/\/excelft.com\/blog"],"url":"https:\/\/excelft.com\/blog\/author\/excelf64_blog\/"}]}},"_links":{"self":[{"href":"https:\/\/excelft.com\/blog\/wp-json\/wp\/v2\/posts\/1036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/excelft.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/excelft.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/excelft.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/excelft.com\/blog\/wp-json\/wp\/v2\/comments?post=1036"}],"version-history":[{"count":1,"href":"https:\/\/excelft.com\/blog\/wp-json\/wp\/v2\/posts\/1036\/revisions"}],"predecessor-version":[{"id":1042,"href":"https:\/\/excelft.com\/blog\/wp-json\/wp\/v2\/posts\/1036\/revisions\/1042"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/excelft.com\/blog\/wp-json\/wp\/v2\/media\/1043"}],"wp:attachment":[{"href":"https:\/\/excelft.com\/blog\/wp-json\/wp\/v2\/media?parent=1036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/excelft.com\/blog\/wp-json\/wp\/v2\/categories?post=1036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/excelft.com\/blog\/wp-json\/wp\/v2\/tags?post=1036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}