{"id":1018,"date":"2019-04-04T18:58:00","date_gmt":"2019-04-04T21:58:00","guid":{"rendered":"https:\/\/excelft.com\/blog\/?p=1018"},"modified":"2025-05-14T09:02:42","modified_gmt":"2025-05-14T12:02:42","slug":"como-evitar-o-roubo-de-combustivel-durante-o-abastecimento-da-frota","status":"publish","type":"post","link":"https:\/\/excelft.com\/blog\/como-evitar-o-roubo-de-combustivel-durante-o-abastecimento-da-frota\/","title":{"rendered":"Como evitar o roubo de combust\u00edvel durante o abastecimento da frota?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">N\u00e3o s\u00e3o apenas casos de fraudes &#8211; interna e externamente &#8211; e desperd\u00edcios que causam preju\u00edzos para a frota. O roubo de combust\u00edvel est\u00e1 entre os principais fatores que impactam negativamente nos lucros e obstruem o crescimento da empresa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inclusive, quando falamos em uma empresa de frotas, esse fator se torna ainda mais relevante. Afinal de contas, os motoristas passam boa parte dos seus dias nas ruas, indo e vindo, e o controle de combust\u00edvel faz parte de toda a log\u00edstica. Ou seja, se esse problema \u00e9 recorrente, voc\u00ea perde em todos os aspectos poss\u00edveis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Deseja erradicar o desvio de combust\u00edvel sob a sua gest\u00e3o? Neste post, apresentaremos algumas solu\u00e7\u00f5es para evitar o roubo de combust\u00edvel durante o abastecimento da frota. Confira e inspire-se em nossas dicas!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Por que uma boa gest\u00e3o \u00e9 importante para evitar o roubo de combust\u00edvel?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Uma pesquisa divulgada pelo Sindicato das Empresas de Transporte de Cargas no Estado do Paran\u00e1 (SETCEPAR) aponta que o preju\u00edzo anual para as empresas que fazem a rota entre S\u00e3o Paulo e Curitiba gira em torno de&nbsp;<a href=\"http:\/\/naboleia.com.br\/setcepar-discute-acoes-contra-roubo-de-combustiveis\/\" target=\"_blank\" rel=\"noreferrer noopener\">R$ 11.400 por caminh\u00e3o<\/a>. Isso apenas com o roubo de combust\u00edvel!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Portanto n\u00e3o se engane, este assunto \u00e9 crucial para o desenvolvimento da sua empresa. E a sua gest\u00e3o tem um impacto significativo no controle de combust\u00edvel e na redu\u00e7\u00e3o de perdas relacionadas a furtos e roubos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Isso \u00e9 poss\u00edvel a partir de uma orienta\u00e7\u00e3o eficaz dos colaboradores, al\u00e9m de um bom sistema de automa\u00e7\u00e3o para garantir informa\u00e7\u00f5es precisas e \u00e1geis para qualificar o seu trabalho. Abaixo, veja algumas recomenda\u00e7\u00f5es interessantes para que a sua rotina seja menos prejudicada por esses fatores limitantes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Dicas para promover a seguran\u00e7a da sua frota<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Reunimos algumas ideias simples e pr\u00e1ticas que podem, em curto ou m\u00e9dio prazo, acabar com o problema relacionado ao roubo de combust\u00edvel. Confira:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Monitore a conduta dos seus motoristas<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Sua parte no crescimento da empresa consiste tamb\u00e9m em orientar a sua equipe, inspir\u00e1-la e ensinar as boas pr\u00e1ticas no exerc\u00edcio da profiss\u00e3o. O que inclui a ado\u00e7\u00e3o de cuidados para evitar o roubo do combust\u00edvel quando estiverem abastecendo em um posto \u00e0 beira da estrada, por exemplo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00f3 que, muitas vezes, esses desvios tamb\u00e9m s\u00e3o motivados internamente. A\u00ed o problema se torna ainda mais grave, j\u00e1 que o preju\u00edzo \u00e9 motivado por quem deveria trabalhar em prol da empresa e n\u00e3o contra ela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Portanto, voc\u00ea deve ser o diferencial: qualifique o processo de recrutamento e sele\u00e7\u00e3o, identifique o perfil de profissionais desejado e batalhe para que, a cada contrata\u00e7\u00e3o, a assertividade seja maior. No dia a dia, treinamentos e capacita\u00e7\u00f5es permitem que voc\u00ea acompanhe o desenvolvimento dos seus profissionais e compreenda quais deles t\u00eam o perfil desejado para seguir na empresa.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Aprenda a diagnosticar o roubo de combust\u00edvel na empresa<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A partir de m\u00e9tricas previamente estabelecidas, voc\u00ea compreende a m\u00e9dia de consumo de combust\u00edvel para cada ve\u00edculo. Um exemplo evidente desse benef\u00edcio \u00e9 que, quando auxiliado por um sistema de automa\u00e7\u00e3o de dados, voc\u00ea j\u00e1 sabe a m\u00e9dia de consumo e consegue compar\u00e1-la com dados mais recentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se houve um aumento consider\u00e1vel no consumo, algo est\u00e1 errado. A\u00ed entra o trabalho de identificar o problema para saber se houve, de fato, roubo de combust\u00edvel ou problemas de log\u00edstica que culminaram nessa mudan\u00e7a significativa.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Mantenha o controle das rotas<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Como um complemento ao t\u00f3pico anterior, voc\u00ea pode seguir o controle das rotas com diversas solu\u00e7\u00f5es tecnol\u00f3gicas e, assim, avaliar rapidamente se os motoristas seguiram o roteiro ou desviaram do caminho. Se, mesmo assim, o problema de roubo de combust\u00edvel acontecer, algumas suspeitas j\u00e1 foram erradicadas, agilizando, portanto, a resolu\u00e7\u00e3o do problema.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Trabalhe para impedir os abastecimentos irregulares<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Mais uma vez: se voc\u00ea conhece as principais m\u00e9tricas para monitorar e, assim, acompanhar o controle de combust\u00edvel, o seu trabalho \u00e9 facilitado at\u00e9 mesmo no momento em que os motoristas abastecem os seus ve\u00edculos. Um exemplo: ao programar as paradas para abastecer os ve\u00edculos, bem como os registros de cada servi\u00e7o realizado, voc\u00ea tem em m\u00e3os todos os dados necess\u00e1rios para investigar qualquer irregularidade ao longo do tempo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Perceba, aqui, o quanto \u00e9 importante dispor de uma equipe qualificada e tamb\u00e9m de um software que agregue valor \u00e0 tomada de decis\u00e3o. Afinal de contas, com tantos dados gerados em pouco tempo, e simultaneamente, \u00e9 fundamental dispor de uma solu\u00e7\u00e3o que compile, organize e armazene esses dados.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Tenha uma boa gest\u00e3o de manuten\u00e7\u00e3o dos ve\u00edculos<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m do roubo de combust\u00edvel, o preju\u00edzo pode ser motivado por um desempenho inferior de alguns ve\u00edculos da sua frota. O que nos leva a perguntar: como \u00e9 a sua gest\u00e3o de manuten\u00e7\u00e3o?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por meio dela, \u00e9 poss\u00edvel reduzir a ocorr\u00eancia de paradas s\u00fabitas devido a um problema mec\u00e2nico, por exemplo, e minimizar os desperd\u00edcios e preju\u00edzos decorrentes disso. Quando se est\u00e1 em dia com as manuten\u00e7\u00f5es, qualquer desvio de combust\u00edvel pode ser avaliado com mais efic\u00e1cia e agilidade. Portanto, trata-se de um investimento imprescind\u00edvel para manter o n\u00edvel de excel\u00eancia dos seus servi\u00e7os e saber como proceder diante de um eventual roubo de combust\u00edvel.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Utilize a tecnologia para acabar com o roubo de combust\u00edvel<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ao longo deste artigo, n\u00f3s mencionamos muito esse diferencial, o que fez com que as solu\u00e7\u00f5es tecnol\u00f3gicas assumissem uma posi\u00e7\u00e3o de destaque nesta seleta lista. Por meio de uma solu\u00e7\u00e3o espec\u00edfica para o controle de combust\u00edvel, voc\u00ea ganha automa\u00e7\u00e3o e precis\u00e3o na sua gest\u00e3o. Entre os benef\u00edcios disso, podemos citar:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>controle total sobre os ve\u00edculos da sua frota;<\/li>\n\n\n\n<li>integra\u00e7\u00e3o de dados em uma s\u00f3 plataforma;<\/li>\n\n\n\n<li>conectividade para lidar com os dados em tempo real, agilizando o planejamento e a tomada de decis\u00e3o;<\/li>\n\n\n\n<li>economia, com o tempo, traduzindo-se em menos desperd\u00edcios e no controle contra o roubo de combust\u00edvel.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Tudo isso com solu\u00e7\u00f5es personalizadas, que se adaptam facilmente \u00e0s suas necessidades e objetivos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quer saber outras dicas para acabar com o roubo de combust\u00edvel da sua frota e otimizar todo o fluxo de trabalho na sua empresa? Aproveite para\u00a0<a href=\"https:\/\/www.facebook.com\/excelbr.pneutronic\" target=\"_blank\" rel=\"noreferrer noopener\">curtir a nossa p\u00e1gina no Facebook<\/a>\u00a0e\u00a0<a href=\"https:\/\/www.youtube.com\/channel\/UCp6C1bjZIm3437k9xQ90OSw\" target=\"_blank\" rel=\"noreferrer noopener\">cadastrar-se em nosso canal do YouTube<\/a>\u00a0para ficar sempre por dentro de todas as nossas novidades!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>N\u00e3o s\u00e3o apenas casos de fraudes &#8211; interna e externamente &#8211; e desperd\u00edcios que causam preju\u00edzos para a frota. O [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1273,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-1018","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gtfrota"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Como evitar o roubo de combust\u00edvel durante o abastecimento da frota? - EXCEL - blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/excelft.com\/blog\/como-evitar-o-roubo-de-combustivel-durante-o-abastecimento-da-frota\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como evitar o roubo de combust\u00edvel durante o abastecimento da frota? - EXCEL - blog\" \/>\n<meta property=\"og:description\" content=\"N\u00e3o s\u00e3o apenas casos de fraudes &#8211; interna e externamente &#8211; e desperd\u00edcios que causam preju\u00edzos para a frota. O [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/excelft.com\/blog\/como-evitar-o-roubo-de-combustivel-durante-o-abastecimento-da-frota\/\" \/>\n<meta property=\"og:site_name\" content=\"EXCEL - blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/excelfueling\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-04T21:58:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-14T12:02:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/excelft.com\/blog\/wp-content\/uploads\/2019\/04\/full-shot-man-gas-station.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Excelbr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Excelbr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/como-evitar-o-roubo-de-combustivel-durante-o-abastecimento-da-frota\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/como-evitar-o-roubo-de-combustivel-durante-o-abastecimento-da-frota\\\/\"},\"author\":{\"name\":\"Excelbr\",\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/#\\\/schema\\\/person\\\/c16241bead34264d4bed13f3d08e43d4\"},\"headline\":\"Como evitar o roubo de combust\u00edvel durante o abastecimento da frota?\",\"datePublished\":\"2019-04-04T21:58:00+00:00\",\"dateModified\":\"2025-05-14T12:02:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/como-evitar-o-roubo-de-combustivel-durante-o-abastecimento-da-frota\\\/\"},\"wordCount\":1122,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/como-evitar-o-roubo-de-combustivel-durante-o-abastecimento-da-frota\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/excelft.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/full-shot-man-gas-station.jpg\",\"articleSection\":[\"GTFrota\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/excelft.com\\\/blog\\\/como-evitar-o-roubo-de-combustivel-durante-o-abastecimento-da-frota\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/como-evitar-o-roubo-de-combustivel-durante-o-abastecimento-da-frota\\\/\",\"url\":\"https:\\\/\\\/excelft.com\\\/blog\\\/como-evitar-o-roubo-de-combustivel-durante-o-abastecimento-da-frota\\\/\",\"name\":\"Como evitar o roubo de combust\u00edvel durante o abastecimento da frota? - EXCEL - blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/como-evitar-o-roubo-de-combustivel-durante-o-abastecimento-da-frota\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/como-evitar-o-roubo-de-combustivel-durante-o-abastecimento-da-frota\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/excelft.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/full-shot-man-gas-station.jpg\",\"datePublished\":\"2019-04-04T21:58:00+00:00\",\"dateModified\":\"2025-05-14T12:02:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/como-evitar-o-roubo-de-combustivel-durante-o-abastecimento-da-frota\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/excelft.com\\\/blog\\\/como-evitar-o-roubo-de-combustivel-durante-o-abastecimento-da-frota\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/como-evitar-o-roubo-de-combustivel-durante-o-abastecimento-da-frota\\\/#primaryimage\",\"url\":\"https:\\\/\\\/excelft.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/full-shot-man-gas-station.jpg\",\"contentUrl\":\"https:\\\/\\\/excelft.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/full-shot-man-gas-station.jpg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/como-evitar-o-roubo-de-combustivel-durante-o-abastecimento-da-frota\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/excelft.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como evitar o roubo de combust\u00edvel durante o abastecimento da frota?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/excelft.com\\\/blog\\\/\",\"name\":\"EXCEL - blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/excelft.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/#organization\",\"name\":\"EXCEL - blog\",\"url\":\"https:\\\/\\\/excelft.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/excelft.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/logo-excel.svg\",\"contentUrl\":\"https:\\\/\\\/excelft.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/logo-excel.svg\",\"width\":307,\"height\":69,\"caption\":\"EXCEL - blog\"},\"image\":{\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/excelfueling\",\"https:\\\/\\\/www.instagram.com\\\/excelfueling\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/excelfueling\\\/?originalSubdomain=br\",\"https:\\\/\\\/www.youtube.com\\\/excelfueling\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/excelft.com\\\/blog\\\/#\\\/schema\\\/person\\\/c16241bead34264d4bed13f3d08e43d4\",\"name\":\"Excelbr\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe7094acce8e1b37ade139ea296076c201aa729da7efc22f68286dfdede38d99?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe7094acce8e1b37ade139ea296076c201aa729da7efc22f68286dfdede38d99?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe7094acce8e1b37ade139ea296076c201aa729da7efc22f68286dfdede38d99?s=96&d=mm&r=g\",\"caption\":\"Excelbr\"},\"sameAs\":[\"https:\\\/\\\/excelft.com\\\/blog\"],\"url\":\"https:\\\/\\\/excelft.com\\\/blog\\\/author\\\/excelf64_blog\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como evitar o roubo de combust\u00edvel durante o abastecimento da frota? - EXCEL - blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/excelft.com\/blog\/como-evitar-o-roubo-de-combustivel-durante-o-abastecimento-da-frota\/","og_locale":"pt_BR","og_type":"article","og_title":"Como evitar o roubo de combust\u00edvel durante o abastecimento da frota? - EXCEL - blog","og_description":"N\u00e3o s\u00e3o apenas casos de fraudes &#8211; interna e externamente &#8211; e desperd\u00edcios que causam preju\u00edzos para a frota. O [&hellip;]","og_url":"https:\/\/excelft.com\/blog\/como-evitar-o-roubo-de-combustivel-durante-o-abastecimento-da-frota\/","og_site_name":"EXCEL - blog","article_publisher":"https:\/\/www.facebook.com\/excelfueling","article_published_time":"2019-04-04T21:58:00+00:00","article_modified_time":"2025-05-14T12:02:42+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/excelft.com\/blog\/wp-content\/uploads\/2019\/04\/full-shot-man-gas-station.jpg","type":"image\/jpeg"}],"author":"Excelbr","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Excelbr","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/excelft.com\/blog\/como-evitar-o-roubo-de-combustivel-durante-o-abastecimento-da-frota\/#article","isPartOf":{"@id":"https:\/\/excelft.com\/blog\/como-evitar-o-roubo-de-combustivel-durante-o-abastecimento-da-frota\/"},"author":{"name":"Excelbr","@id":"https:\/\/excelft.com\/blog\/#\/schema\/person\/c16241bead34264d4bed13f3d08e43d4"},"headline":"Como evitar o roubo de combust\u00edvel durante o abastecimento da frota?","datePublished":"2019-04-04T21:58:00+00:00","dateModified":"2025-05-14T12:02:42+00:00","mainEntityOfPage":{"@id":"https:\/\/excelft.com\/blog\/como-evitar-o-roubo-de-combustivel-durante-o-abastecimento-da-frota\/"},"wordCount":1122,"commentCount":0,"publisher":{"@id":"https:\/\/excelft.com\/blog\/#organization"},"image":{"@id":"https:\/\/excelft.com\/blog\/como-evitar-o-roubo-de-combustivel-durante-o-abastecimento-da-frota\/#primaryimage"},"thumbnailUrl":"https:\/\/excelft.com\/blog\/wp-content\/uploads\/2019\/04\/full-shot-man-gas-station.jpg","articleSection":["GTFrota"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/excelft.com\/blog\/como-evitar-o-roubo-de-combustivel-durante-o-abastecimento-da-frota\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/excelft.com\/blog\/como-evitar-o-roubo-de-combustivel-durante-o-abastecimento-da-frota\/","url":"https:\/\/excelft.com\/blog\/como-evitar-o-roubo-de-combustivel-durante-o-abastecimento-da-frota\/","name":"Como evitar o roubo de combust\u00edvel durante o abastecimento da frota? - EXCEL - blog","isPartOf":{"@id":"https:\/\/excelft.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/excelft.com\/blog\/como-evitar-o-roubo-de-combustivel-durante-o-abastecimento-da-frota\/#primaryimage"},"image":{"@id":"https:\/\/excelft.com\/blog\/como-evitar-o-roubo-de-combustivel-durante-o-abastecimento-da-frota\/#primaryimage"},"thumbnailUrl":"https:\/\/excelft.com\/blog\/wp-content\/uploads\/2019\/04\/full-shot-man-gas-station.jpg","datePublished":"2019-04-04T21:58:00+00:00","dateModified":"2025-05-14T12:02:42+00:00","breadcrumb":{"@id":"https:\/\/excelft.com\/blog\/como-evitar-o-roubo-de-combustivel-durante-o-abastecimento-da-frota\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/excelft.com\/blog\/como-evitar-o-roubo-de-combustivel-durante-o-abastecimento-da-frota\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/excelft.com\/blog\/como-evitar-o-roubo-de-combustivel-durante-o-abastecimento-da-frota\/#primaryimage","url":"https:\/\/excelft.com\/blog\/wp-content\/uploads\/2019\/04\/full-shot-man-gas-station.jpg","contentUrl":"https:\/\/excelft.com\/blog\/wp-content\/uploads\/2019\/04\/full-shot-man-gas-station.jpg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/excelft.com\/blog\/como-evitar-o-roubo-de-combustivel-durante-o-abastecimento-da-frota\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/excelft.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Como evitar o roubo de combust\u00edvel durante o abastecimento da frota?"}]},{"@type":"WebSite","@id":"https:\/\/excelft.com\/blog\/#website","url":"https:\/\/excelft.com\/blog\/","name":"EXCEL - blog","description":"","publisher":{"@id":"https:\/\/excelft.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/excelft.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/excelft.com\/blog\/#organization","name":"EXCEL - blog","url":"https:\/\/excelft.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/excelft.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/logo-excel.svg","contentUrl":"https:\/\/excelft.com\/blog\/wp-content\/uploads\/2024\/09\/logo-excel.svg","width":307,"height":69,"caption":"EXCEL - blog"},"image":{"@id":"https:\/\/excelft.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/excelfueling","https:\/\/www.instagram.com\/excelfueling","https:\/\/www.linkedin.com\/company\/excelfueling\/?originalSubdomain=br","https:\/\/www.youtube.com\/excelfueling"]},{"@type":"Person","@id":"https:\/\/excelft.com\/blog\/#\/schema\/person\/c16241bead34264d4bed13f3d08e43d4","name":"Excelbr","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/fe7094acce8e1b37ade139ea296076c201aa729da7efc22f68286dfdede38d99?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fe7094acce8e1b37ade139ea296076c201aa729da7efc22f68286dfdede38d99?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe7094acce8e1b37ade139ea296076c201aa729da7efc22f68286dfdede38d99?s=96&d=mm&r=g","caption":"Excelbr"},"sameAs":["https:\/\/excelft.com\/blog"],"url":"https:\/\/excelft.com\/blog\/author\/excelf64_blog\/"}]}},"_links":{"self":[{"href":"https:\/\/excelft.com\/blog\/wp-json\/wp\/v2\/posts\/1018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/excelft.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/excelft.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/excelft.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/excelft.com\/blog\/wp-json\/wp\/v2\/comments?post=1018"}],"version-history":[{"count":1,"href":"https:\/\/excelft.com\/blog\/wp-json\/wp\/v2\/posts\/1018\/revisions"}],"predecessor-version":[{"id":1019,"href":"https:\/\/excelft.com\/blog\/wp-json\/wp\/v2\/posts\/1018\/revisions\/1019"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/excelft.com\/blog\/wp-json\/wp\/v2\/media\/1273"}],"wp:attachment":[{"href":"https:\/\/excelft.com\/blog\/wp-json\/wp\/v2\/media?parent=1018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/excelft.com\/blog\/wp-json\/wp\/v2\/categories?post=1018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/excelft.com\/blog\/wp-json\/wp\/v2\/tags?post=1018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}